{"id":262,"date":"2016-11-29T03:20:22","date_gmt":"2016-11-29T03:20:22","guid":{"rendered":"http:\/\/travelwp.physcode.com\/maindemo\/product\/wwi-battlefields\/"},"modified":"2025-02-08T10:29:40","modified_gmt":"2025-02-08T15:29:40","slug":"llanganuco","status":"publish","type":"product","link":"https:\/\/explorehuaraz.com\/es\/tours\/llanganuco","title":{"rendered":"Laguna LLanganuco"},"content":{"rendered":"<p>Uno de los atractivos m\u00e1s hermosos de la Cordillera Blanca, laguna en la que podremos tomar buenas fotograf\u00edas, hacer paseo en bote al mismo tiempo que nos aclimatamos a la altura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aliquam lacus nisl, viverra convallis sit amet\u00a0penatibus nunc\u00a0luctus<\/p>\n","protected":false},"featured_media":8897,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-262","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"tour_phys-tours-fullday","7":"product_cat-tours-diarios","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-tour_phys"},"_links":{"self":[{"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/product\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/comments?post=262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/media\/8897"}],"wp:attachment":[{"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/product_brand?post=262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/product_cat?post=262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/explorehuaraz.com\/es\/wp-json\/wp\/v2\/product_tag?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}